{"id":2067,"date":"2022-08-28T19:51:43","date_gmt":"2022-08-28T17:51:43","guid":{"rendered":"https:\/\/www.brainycommerce.com\/?p=2067"},"modified":"2023-02-22T13:13:08","modified_gmt":"2023-02-22T12:13:08","slug":"amazon-style-phygital","status":"publish","type":"post","link":"https:\/\/www.brainycommerce.com\/es\/info\/amazon-style-phygital\/","title":{"rendered":"Amazon Style, una visi\u00f3n phygital que ofrece lo mejor de cada mundo"},"content":{"rendered":"<figure id=\"attachment_2068\" aria-describedby=\"caption-attachment-2068\" style=\"width: 225px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2068 size-medium\" title=\"Visita a Amazon Style\" src=\"https:\/\/www.brainycommerce.com\/wp-content\/uploads\/2022\/08\/Entrada-Amazon-Style-225x300.jpg\" alt=\"Nuestro CEO, Miguel de Reina, nos cuenta su visita a Amazon Style\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.brainycommerce.com\/wp-content\/uploads\/2022\/08\/Entrada-Amazon-Style-225x300.jpg 225w, https:\/\/www.brainycommerce.com\/wp-content\/uploads\/2022\/08\/Entrada-Amazon-Style-768x1024.jpg 768w, https:\/\/www.brainycommerce.com\/wp-content\/uploads\/2022\/08\/Entrada-Amazon-Style-1152x1536.jpg 1152w, https:\/\/www.brainycommerce.com\/wp-content\/uploads\/2022\/08\/Entrada-Amazon-Style-1536x2048.jpg 1536w, https:\/\/www.brainycommerce.com\/wp-content\/uploads\/2022\/08\/Entrada-Amazon-Style-600x800.jpg 600w, https:\/\/www.brainycommerce.com\/wp-content\/uploads\/2022\/08\/Entrada-Amazon-Style-scaled.jpg 1920w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><figcaption id=\"caption-attachment-2068\" class=\"wp-caption-text\">Visita a Amazon Style<\/figcaption><\/figure>\n<p>Este verano tuve la oportunidad de pasarlo con mi familia en California. Una experiencia inolvidable para todos. Y aprovech\u00e9 la tecnol\u00f3gica zona para satisfacer algunas curiosidades profesionales, como visitar la primera tienda f\u00edsica Amazon Style del mundo.<\/p>\n<p>Una parada profesional que me cost\u00f3 muy poco colarles ya que son todo mujeres. En realidad estaba proponiendo ir una ma\u00f1ana de compras:-).<\/p>\n<h3>El Primer Amazon Style<\/h3>\n<p>La andadura de Amazon Style, comenz\u00f3 el <a href=\"https:\/\/www.aboutamazon.com\/news\/retail\/amazon-reimagines-in-store-shopping-with-amazon-style\">25 de mayo de 2022<\/a> en la ciudad de Glendale, a tan solo 15 minutos en coche del centro de Los \u00c1ngeles.<\/p>\n<p>Y este es el video oficial de Amazon sobre el nuevo concepto:<\/p>\n<div class=\"wpex-responsive-media\"><iframe loading=\"lazy\" title=\"Introducing Amazon Style\u2014Amazon&#039;s first physical store for men&#039;s and women&#039;s fashion\" width=\"980\" height=\"551\" src=\"https:\/\/www.youtube.com\/embed\/c67K8JO1WJE?feature=oembed\"  allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/div>\n<p>\u201c<em>It\u00b4s their first brick-and-mortar apparel store<\/em>\u201d cuentan los medios sobre su apertura (para los que llevamos unos a\u00f1os debatiendo entre <em>dot com<\/em> y <em>brick-a<\/em><em>nd-mortar<\/em> es m\u00e1s impactante leer esto en ingl\u00e9s por lo que, aprovechando la cursilada, dejar\u00e9 algunos p\u00e1rrafos y descripciones en ingl\u00e9s para que pierdan menos su esencia).<\/p>\n<h3>Perfil del consumidor<\/h3>\n<p><a href=\"https:\/\/es.wikipedia.org\/wiki\/Glendale_(California)\">Glendale<\/a> es una poblaci\u00f3n de cerca de 200.000 habitantes con una densidad poblacional de unas de 2.500 personas por km\u00b2. Se encuentra en el extremo oriental del Valle de San Fernando y es un importante suburbio en el \u00c1rea Metropolitana de Los \u00c1ngeles.<\/p>\n<p>Se puede decir que es un barrio muy acomodado donde impresiona la calidad del shopping mall en el que est\u00e1 alojada la tienda, <a href=\"https:\/\/americanaatbrand.com\/\">The Americana at Brand<\/a> (889 Americana Way, Glendale, CA 91210, Estados Unidos)<\/p>\n<p><em>The Americana at Brand offers world-class retail, restaurants, entertainment and residences together in one beautiful destination. An L.A. favorite, it\u2019s a gathering place where friends and family come together to shop, dine and unwind, while enjoying a taste of the good life<\/em>.<\/p>\n<div class=\"wpex-responsive-media\"><iframe loading=\"lazy\" title=\"D&amp;L Amazon Style 1\" width=\"980\" height=\"551\" src=\"https:\/\/www.youtube.com\/embed\/gJJF3HNuoHo?feature=oembed\"  allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/div>\n<h3>Dell Mall al Marketplace y viceversa<\/h3>\n<p>Hace no mucho escrib\u00eda en el blog del Programa de la Publicidad un art\u00edculo titulado \u201c<a href=\"https:\/\/www.programapublicidad.com\/del-mall-al-marketplace-amazon-en-busca-de-la-esencia-perdida-por-miguel-de-reina\/\">Del Mall al Marketplace. Amazon, en busca de la esencia perdida<\/a>\u201d y se puede decir que este shopping mall recupera ese \u201cthird place\u201d donde un americano pasa el tiempo que le queda entre el trabajo y la familia a la vez que gasta su dinero.<\/p>\n<p>La nueva tienda f\u00edsica de Amazon se rodea del mejor ambiente y se codea con las mejores marcas como Apple, Nespresso, Nike, Antrophlogy, Barnes &amp; Noble, Tesla o The Cheesse Cake Factory. \u00a0Aunque tiene de vecina m\u00e1s cercana a un H&amp;M que sale muy desmejorada de la comparativa, comentar\u00e9 al final sobre eso.<\/p>\n<h3>Amazon Style: propuesta de valor<\/h3>\n<p>La propuesta de valor de Amazon Style se define como \u201c<em>Experience an all-new way to shop for men\u2019s and women\u2019s clothing, shoes and accessories. Amazon Style uses innovative technology to help you find looks you\u2019ll love at the same prices as on Amazon.com<\/em>.\u201d<\/p>\n<p>Y esa es la primera y fundamental sorpresa que me llev\u00e9 de la visita y s\u00e9 que no deber\u00eda porque eso es justo lo que es y representa Amazon \u201cinnovaci\u00f3n y tecnolog\u00eda\u201d pero cre\u00eda que iba a encontrar algo diferente a esto.<\/p>\n<p>En los \u00faltimos meses\/a\u00f1os venimos asistiendo a un intenso debate sobre c\u00f3mo debe evolucionar el mundo del retail tradicional y en especial el retail moda en relaci\u00f3n con la progresiva digitalizaci\u00f3n de la sociedad y el crecimiento imparable del comercio electr\u00f3nico.<\/p>\n<p>Hemos pasado de una nunca lograda omnicanalidad a un nuevo concepto mucho mejor definido, m\u00e1s certero con la realidad que vivimos como consumidores. M\u00e1s sencillo de entender, pero a\u00fan m\u00e1s complejo de llevar a cabo como lo <a href=\"https:\/\/es.wikipedia.org\/wiki\/Phygital\">Phygital .<\/a> <span style=\"font-size: 10pt;\"><em>(presencia de una misma persona en el mundo f\u00edsico y en el \u00e1mbito digital donde\u00a0 su comportamiento es parte de una misma realidad, que debe poder tratarse de forma conjunta o phygital).<\/em><\/span><\/p>\n<h3>Una tienda efectiva, no efectista<\/h3>\n<p>Con la visita a Amazon Style esperaba una puesta en escena m\u00e1s parecida a algunas de las que hemos visto en Europa donde hay marcas, y nuevos conceptos de tienda multimarca, que est\u00e1n creando proyectos que son m\u00e1s \u201clugares experienciales\u201d donde se pretende que el consumidor tenga la oportunidad de relacionarse con la marca de una manera completamente nueva e inmersiva. Propuestas de nuevos espacios con impactantes colores, formas, sonidos y olores que nos invitan a \u201cvivir toda la esencia de la marca desde dentro\u201d.<\/p>\n<p>Bueno, pues Amazon Style no es nada de eso.<\/p>\n<p>La propuesta de Amazon va de reducir todos los inconvenientes e incomodidades que tenemos hoy cuando visitamos una tienda de ropa y hacerlo a base de innovaci\u00f3n, operaciones y tecnolog\u00eda.<\/p>\n<h3>Todo comodidades<\/h3>\n<p>Una nueva experiencia llena para elegir, probar y pagar prendas de vestir y accesorios ideada pensando en la comodidad. As\u00ed lo cuenta uno de sus Amazonians:<\/p>\n<div class=\"wpex-responsive-media\"><iframe loading=\"lazy\" title=\"Amazon Style Shop_How it works\" width=\"980\" height=\"551\" src=\"https:\/\/www.youtube.com\/embed\/XEBRNdItwJI?feature=oembed\"  allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/div>\n<p>Es decir, fuera aglomeraciones, el desorden, la falta de informaci\u00f3n, no saber que comprar, cargar con la ropa por la tienda, el buscarlo en paralelo en Internet, el no encontrar tallas, el lamentable momento probador, colas al pagar, el ticket papel etc\u2026<\/p>\n<p>En realidad, son dos tiendas, dos caras de una misma moneda. Dos mundos separados \u00a0y a la vez unidos por los probadores que pasan de ser un lugar m\u00e1s o menos cutre y peque\u00f1o con puerta y espejo donde meterte con un mogoll\u00f3n de prendas a un lugar amplio, tecnol\u00f3gico, privado, agradable, personalizado y m\u00e1gico donde acabas tomando las mejores decisiones de compra sin agobios de ning\u00fan tipo.<\/p>\n<h3>Y as\u00ed lo vivimos nosotros<\/h3>\n<p>Vas por la tienda con tu m\u00f3vil, en el que previamente te has descargado la App de Amazon Style. Tambi\u00e9n puedes usar el lector de QR de la App de Amazon, yo solo tuve que cambiar el pa\u00eds, escanear cualquier prenda y voila!, ya est\u00e1s en Amazon Style Glendale.<\/p>\n<p>Escaneas las prendas que te gustan, eliges talla y color en tu m\u00f3vil y as\u00ed las vas pidiendo para prob\u00e1rtelas\u2026A los pocos minutos de seleccionar la primera, te llegan una notificaci\u00f3n&#8230;\u00bbbuscando tu probador\u00bb, y minutos despu\u00e9s que ya tienes tu probador listo con tus prendas elegidas esper\u00e1ndote para prob\u00e1rtelas.<\/p>\n<p>El caso es que mientras t\u00fa te mueves por la tienda seleccionando art\u00edculos, otro equipo humano y robotizado de Amazon est\u00e1 trabajando detr\u00e1s de los probadores para llevar al tuyo personal todo lo que te quieres probar.<\/p>\n<p>Y no solo lo que has localizado t\u00fa, tambi\u00e9n te vas a encontrar prendas similares, sugerencias que el algoritmo de la tienda, y el de Amazon en base a tu perfil, ha considerado que ser\u00e1n de tu inter\u00e9s.<\/p>\n<p>Espera, te lo cuento con un video:<\/p>\n<div class=\"wpex-responsive-media\"><iframe loading=\"lazy\" title=\"Brainy Amazon Style_Our experience\" width=\"980\" height=\"551\" src=\"https:\/\/www.youtube.com\/embed\/xiHnM4xFo7o?feature=oembed\"  allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/div>\n<p>Por si no puedes ver el video ahora y para que el texto indexe en el SEO de nuestro blog:-), te lo sigo contando&#8230;<\/p>\n<p>Cuando decides entrar a los probadores,\u00a0 lo haces sin una sola prenda en la mano, sin una d\u00e9cima de segundo de espera y sin ser irrespetuosamente vigilado por ning\u00fan dependiente que cuente sospechosamente con cuantas prendas entras o sales.<\/p>\n<p>Pones tu m\u00f3vil encima del pomo de la puerta de TU probador \u00a0y \u00a1\u00a1se abre!!.<\/p>\n<h3>Una experiencia&#8230;Phygital \u00bfo es magia?<\/h3>\n<p>Al entrar, una gran pantalla te da la bienvenida \u201cWelcome to your room, Miguel\u201d. La pantalla, que es grande y t\u00e1ctil, tiene toda la informaci\u00f3n de lo que llevas visitado y seleccionado por lo que no te vuelves a acordar del m\u00f3vil.<\/p>\n<p>En las perchas est\u00e1n todas las prendas escogidas en sus tallas. \u00a1Y las recomendaciones!, es como disponer de ayuda experta y con profesi\u00f3n, algo raro de encontrar hoy en una tienda.<\/p>\n<p>Empiezas a probarte cosas y comienza el juego del espejo y la pantalla t\u00e1ctil. Los duendes van incorporando tus deseos al un apartado privado del armario y te avisa con golpecitos que ya puedes abrir y seguir prob\u00e1ndote prendas.<\/p>\n<p>Solo falta la Coca Cola y las patatas y \u00a1te quedar\u00edas toda la tarde ah\u00ed dentro!.<\/p>\n<p>\u00a1Es otro rollo!. Una de mis hijas eligi\u00f3 una sudadera y otra unas gafas de sol. La prenda qued\u00f3 elegida en el probador, el accesorio paseando la tienda, todo a la misma cesta. Mismos art\u00edculos, ASIN y precios que en amazon.com<\/p>\n<p>Salimos del probador solo con nuestras compras y dejamos todo el resto all\u00ed, al cerrar la puerta o\u00edmos como el personal de Amazon devolv\u00eda el espacio a su estado original..<\/p>\n<p>Pagar es tan f\u00e1cil como \u201ctramitar pedido\u201d en la app, una sonrisa, una bolsa (de papel reciclado) de Amazon Style, te llega el recibo al m\u00f3vil y listo. Cero colas y cero esperas. Todo facilidades.<\/p>\n<h3>Paga con la mano: Amazon One<\/h3>\n<p>\u00bfY si te has olvidado el m\u00f3vil y la cartera? \u00a1pagas con la mano! s\u00ed, con la palma de la mano, gracias a <a href=\"https:\/\/one.amazon.com\/\">Amazon One<\/a>, un sistema de reconocimiento biom\u00e9trico donde el usuario usa la palma de su mano para pagar los productos a trav\u00e9s de su propia huella.<\/p>\n<div class=\"wpex-responsive-media\"><iframe loading=\"lazy\" title=\"Amazon One: an easier way through your day\" width=\"980\" height=\"551\" src=\"https:\/\/www.youtube.com\/embed\/xH_SVNVIfzk?feature=oembed\"  allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/div>\n<h3>Amazon y los Influencers<\/h3>\n<figure id=\"attachment_2074\" aria-describedby=\"caption-attachment-2074\" style=\"width: 300px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2074 size-medium\" title=\"Amazon Style y los Influencers\" src=\"https:\/\/www.brainycommerce.com\/wp-content\/uploads\/2022\/08\/Amazon-Style-Influencers-300x300.jpg\" alt=\"Apuesta decidida de Amazon para utilizar influencers y redes sociales como generadores de tr\u00e1fico y prescripci\u00f3n\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.brainycommerce.com\/wp-content\/uploads\/2022\/08\/Amazon-Style-Influencers-300x300.jpg 300w, https:\/\/www.brainycommerce.com\/wp-content\/uploads\/2022\/08\/Amazon-Style-Influencers-150x150.jpg 150w, https:\/\/www.brainycommerce.com\/wp-content\/uploads\/2022\/08\/Amazon-Style-Influencers-768x768.jpg 768w, https:\/\/www.brainycommerce.com\/wp-content\/uploads\/2022\/08\/Amazon-Style-Influencers.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-2074\" class=\"wp-caption-text\">Amazon y los Influencers<\/figcaption><\/figure>\n<p>Para los indecisos o los que prefieren dejarse influir, tambi\u00e9n hay ayuda. Lo primero que ves al entrar son una serie de paneles con \u201c<em>outfits<\/em>\u201d elaborados por Influencers con prendas que est\u00e1n a la venta en la tienda. Un QR te permite visitar sus perfiles.<\/p>\n<p>Amazon trabaja en conquistar, tambi\u00e9n, las redes sociales. Un camino ya comenzado hace alg\u00fan tiempo en moda y que est\u00e1 ya en Espa\u00f1a con \u201c<a href=\"https:\/\/www.amazon.es\/thedrop\">The Drop<\/a>\u201d.<\/p>\n<p>El influencer como personal shopper en la propia tienda, la prescripci\u00f3n, el tr\u00e1fico dirigido al canal online u off line desde sus propias redes sociales, el marketing de afiliados con el influencer, etc, etc..<\/p>\n<h3>La batalla de las plataformas de red<\/h3>\n<p>Tremenda la batalla que gracias a este movimiento y a otros similares puede plantear Amazon en cuanto a fuga de Influencers de Instagram, que se podr\u00eda parecer a la que se libra en este momento entre Youtubers y Twitchers. La lucha de las plataformas de red continua\u2026.<\/p>\n<p>Cuando sal\u00edamos fascinados con la experiencia, pasamos por delante de la puerta de H&amp;M, solo asomarte da pereza, es como volver al pasado y ni entramos.<\/p>\n<h3>Conclusiones y aprendizajes m\u00e1s all\u00e1 de la tecnolog\u00eda<\/h3>\n<p>Mi resumen es que Amazon Style es una tienda multimarca que ofrece muy buena experiencia de usuario y que esto puede ser un gran atractivo que siga empujando el crecimiento de Amazon en Apparel en un mundo de canales integrados.<\/p>\n<p>Y como resumen para los clientes de <a href=\"http:\/\/www.brainycommerce.com\">Brainy Commerce<\/a> y sobre todo a las marcas que hoy dudan de si incorporar a Amazon en su estrategia de ecommerce les dar\u00eda tres mensajes:<\/p>\n<ol>\n<li>Amazon ya no es solo un ecommerce, Amazon es sobre todo \u201ccustomer obsession\u201d.<\/li>\n<li>Que utilizarles como canal de venta hoy es llegar a millones usuarios de internet incrementando tus ventas pero que pronto podr\u00eda suponer estar tambi\u00e9n a la venta en sus tiendas f\u00edsicas.<\/li>\n<li>Que mientras estas a la venta en sus plataformas y tiendas, puedes entender c\u00f3mo trabajan y lograr aprendizajes que puede ser de gran ayuda en tu proceso de transformaci\u00f3n\u2026phygital.<\/li>\n<\/ol>\n<h4 style=\"text-align: center;\">\u00a1Ojo a lo que nos viene\u2026It&#8217;s still day one!<\/h4>\n<p><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Visita a la primera tienda Amazon Style del mundo. Integraci\u00f3n de canales de compra pensando solo en el consumidor phygital.<\/p>\n","protected":false},"author":5,"featured_media":2093,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","inline_featured_image":false,"footnotes":""},"categories":[106],"tags":[92,84,62,59],"class_list":["post-2067","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-que-es","tag-amazon","tag-amazon-apparel","tag-ecommerce","tag-retail","entry","has-media"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.brainycommerce.com\/es\/wp-json\/wp\/v2\/posts\/2067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brainycommerce.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brainycommerce.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brainycommerce.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brainycommerce.com\/es\/wp-json\/wp\/v2\/comments?post=2067"}],"version-history":[{"count":3,"href":"https:\/\/www.brainycommerce.com\/es\/wp-json\/wp\/v2\/posts\/2067\/revisions"}],"predecessor-version":[{"id":2755,"href":"https:\/\/www.brainycommerce.com\/es\/wp-json\/wp\/v2\/posts\/2067\/revisions\/2755"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brainycommerce.com\/es\/wp-json\/wp\/v2\/media\/2093"}],"wp:attachment":[{"href":"https:\/\/www.brainycommerce.com\/es\/wp-json\/wp\/v2\/media?parent=2067"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brainycommerce.com\/es\/wp-json\/wp\/v2\/categories?post=2067"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brainycommerce.com\/es\/wp-json\/wp\/v2\/tags?post=2067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}